{"id":1696,"date":"2022-02-08T14:05:27","date_gmt":"2022-02-08T14:05:27","guid":{"rendered":"https:\/\/www.elsrochette.brussels\/?p=1696"},"modified":"2022-02-10T13:39:44","modified_gmt":"2022-02-10T13:39:44","slug":"resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen","status":"publish","type":"post","link":"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/","title":{"rendered":"Fusion des zones de police bruxelloises : pourquoi nous ne soutenons pas la r\u00e9solution de la N-VA"},"content":{"rendered":"<p><strong>Sommes-nous pour la fusion des zones de police bruxelloises ? Bien entendu. La r\u00e9solution de la N-VA est-elle la meilleure voie \u00e0 suivre ? Non. Nous nous sommes donc abstenus lors du vote.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Il faut se d\u00e9faire du regard \u00e9troitement communautaire sur cette question et parler davantage d\u2019efficacit\u00e9. <\/p><\/blockquote>\n\n\n\n<p>La N-VA a pr\u00e9sent\u00e9 un <a href=\"http:\/\/www.parlement.brussels\/weblex-doc-det\/?moncode=PF580&amp;montitre=A-148\/1-19\/20&amp;base=1&amp;taal=nd&amp;lang=nl\">r\u00e9solution<\/a> pour la fusion des zones de police bruxelloises. one.brussels est pour la fusion, mais aussi pour un fort ancrage local. <\/p>\n\n\n\n<p>Et ce projet de r\u00e9solution ne contribuera pas \u00e0 ce type de r\u00e9forme n\u00e9cessaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"waarom-onthielden-we-ons-bij-de-stemming\">Pourquoi nous \u00eatre abstenus lors du vote ?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"gewogen-en-te-licht-bevonden\">Modeste et l\u00e9g\u00e8re<\/h3>\n\n\n\n<p>La r\u00e9solution de la N-VA est mal \u00e9tay\u00e9e. Elle cite beaucoup d\u2019articles de presse. Rien n\u2019y est pr\u00e9cis\u00e9 quant \u00e0 la mani\u00e8re dont la r\u00e9forme doit se faire, \u00e0 ce qui est n\u00e9cessaire pour pr\u00e9server l\u2019expertise locale ou aux \u00e9ventuelles cons\u00e9quences en mati\u00e8re de financement ou de personnel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"de-resolutie-zal-niets-opleveren\">Cette r\u00e9solution ne r\u00e9soudra rien<\/h3>\n\n\n\n<p>La N-VA campe sur sa position : \u00ab c\u2019est comme \u00e7a et pas autrement \u00bb. Mais cette approche ne r\u00e9soudra rien.<\/p>\n\n\n\n<p>Malheureusement, la fusion des zones de police est souvent consid\u00e9r\u00e9e comme une question d\u2019opposition entre francophones et n\u00e9erlandophones. Les partis et bourgmestres) francophones s\u2019y opposent l\u00e0 o\u00f9 les n\u00e9erlandophones sont favorables \u00e0 une zone de police unique.&nbsp;<\/p>\n\n\n\n<p>Les Bruxellois, peu importe leur langue, ne comprennent pourtant pas pourquoi les six zones de police continuent \u00e0 exister.&nbsp;<\/p>\n\n\n\n<p>Il faut se d\u00e9faire du regard \u00e9troitement communautaire et parler davantage des mani\u00e8res d\u2019accro\u00eetre l\u2019efficacit\u00e9 et d\u2019am\u00e9liorer le fonctionnement. Autrement dit, consid\u00e9rer la question objectivement sur la base d\u2019une analyse approfondie, scientifiquement et socialement fond\u00e9e.&nbsp;<\/p>\n\n\n\n<p>C\u2019est ce qui fait d\u00e9faut dans cette proposition.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"n-va-is-niet-erg-consequent\">La N-VA pas vraiment cons\u00e9quente<\/h3>\n\n\n\n<p>La N-VA a rat\u00e9 sa chance de fusionner les six zones de police. Au cours de la l\u00e9gislature pr\u00e9c\u00e9dente, c\u2019est elle qui a rempli le poste de Ministre f\u00e9d\u00e9ral de l\u2019Int\u00e9rieur en la personne de Jan Jambon. Il n\u2019a pris aucune initiative en ce sens.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"de-dingen-zijn-in-beweging\">Les lignes bougent<\/h2>\n\n\n\n<p>Mais nous ne restons pas les bras ballants. <\/p>\n\n\n\n<p>\u00c0 la suite de la sixi\u00e8me r\u00e9forme de l\u2019\u00c9tat, un nouvel Organisme d\u2019int\u00e9r\u00eat public r\u00e9gional, Bruxelles Pr\u00e9vention &amp; S\u00e9curit\u00e9, a \u00e9t\u00e9 cr\u00e9\u00e9 lors de la l\u00e9gislature pr\u00e9c\u00e9dente, en charge d\u2019organiser une gestion centralis\u00e9e de la s\u00e9curit\u00e9 et une politique r\u00e9gionale en mati\u00e8re de s\u00e9curit\u00e9.&nbsp;<\/p>\n\n\n\n<p>Brusafe a \u00e9t\u00e9 cr\u00e9\u00e9, l\u2019\u00e9cole r\u00e9gionale des m\u00e9tiers de la s\u00e9curit\u00e9, de la pr\u00e9vention et du secours.<\/p>\n\n\n\n<p>En 2021 est entr\u00e9 en service le centre de crise et de communication, ainsi qu\u2019une plate-forme de vid\u00e9o-surveillance.<\/p>\n\n\n\n<p>Actuellement, les \u00c9tats g\u00e9n\u00e9raux de l'organisation de la police, une initiative de la ministre f\u00e9d\u00e9rale de l'Int\u00e9rieur Annelies Verlinden, sont en cours au niveau f\u00e9d\u00e9ral. La fusion des zones de police de Bruxelles y sera \u00e9voqu\u00e9e. Nous attendons les r\u00e9sultats avec impatience. <a href=\"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/policing-the-future-brussel-denkt-mee\/\">de Staten-Generaal over de&nbsp;organisatie van de politie<\/a>En attendant, Bruxelles doit aussi r\u00e9fl\u00e9chir. \nLa messe n\u2019est pas dite en ce qui concerne la fusion des six zones de police.\nNous sommes pour et continuerons \u00e0 la mettre \u00e0 l'ordre du jour.<\/p>\n\n\n\n<p>Intussen moet Brussel zelf ook denkwerk doen.&nbsp;<\/p>\n\n\n\n<p>Over het samenbrengen van de zes politiezones in \u00e9\u00e9n politiezone is het laatste woord nog niet gezegd.<\/p>\n\n\n\n<p>Wij zijn voor en blijven dit op de agenda zetten.<\/p>","protected":false},"excerpt":{"rendered":"Zijn we voor de \u00e9\u00e9nmaking van de Brussels politiezones? Ja. Is de resolutie van N-VA de beste weg? Nee. Daarom hebben we ons onthouden bij de stemming. We moeten af van de starre communautaire kijk op de zaak, maar het hebben over meer effici\u00ebntie en beter werken. De N-VA diende een resolutie in voor een&#8230; <a class=\"meer\" href=\"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/\">Lees meer<\/a>","protected":false},"author":1,"featured_media":959,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pact-voor-brussel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>E\u00e9nmaking van de Brusselse politiezones: waarom we de resolutie van N-VA niet steunen - Els Rochette<\/title>\n<meta name=\"description\" content=\"one.brussels is voor een fusie van de zes Brusselse politiezones. Maar het voorstel van resolutie dat is voorgelegd, zal dat niet realiseren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E\u00e9nmaking van de Brusselse politiezones: waarom we de resolutie van N-VA niet steunen - Els Rochette\" \/>\n<meta property=\"og:description\" content=\"one.brussels is voor een fusie van de zes Brusselse politiezones. Maar het voorstel van resolutie dat is voorgelegd, zal dat niet realiseren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/\" \/>\n<meta property=\"og:site_name\" content=\"Els Rochette\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-08T14:05:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-10T13:39:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/02\/7S9A8816.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"1653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robin CUVILLIER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"one.brussels is voor een fusie van de zes Brusselse politiezones. Maar het voorstel van resolutie dat is voorgelegd, zal dat niet realiseren.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/02\/7S9A8816.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robin CUVILLIER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/\",\"url\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/\",\"name\":\"E\u00e9nmaking van de Brusselse politiezones: waarom we de resolutie van N-VA niet steunen - Els Rochette\",\"isPartOf\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A8816.jpg\",\"datePublished\":\"2022-02-08T14:05:27+00:00\",\"dateModified\":\"2022-02-10T13:39:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\"},\"description\":\"one.brussels is voor een fusie van de zes Brusselse politiezones. Maar het voorstel van resolutie dat is voorgelegd, zal dat niet realiseren.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/#primaryimage\",\"url\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A8816.jpg\",\"contentUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A8816.jpg\",\"width\":2480,\"height\":1653},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elsrochette.brussels\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E\u00e9nmaking van de Brusselse politiezones: waarom we de resolutie van N-VA niet steunen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\",\"url\":\"https:\/\/www.elsrochette.brussels\/\",\"name\":\"Els Rochette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elsrochette.brussels\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\",\"name\":\"Robin CUVILLIER\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E\u00e9nmaking van de Brusselse politiezones: waarom we de resolutie van N-VA niet steunen - Els Rochette","description":"one.brussels is voor een fusie van de zes Brusselse politiezones. Maar het voorstel van resolutie dat is voorgelegd, zal dat niet realiseren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/","og_locale":"fr_FR","og_type":"article","og_title":"E\u00e9nmaking van de Brusselse politiezones: waarom we de resolutie van N-VA niet steunen - Els Rochette","og_description":"one.brussels is voor een fusie van de zes Brusselse politiezones. Maar het voorstel van resolutie dat is voorgelegd, zal dat niet realiseren.","og_url":"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/","og_site_name":"Els Rochette","article_published_time":"2022-02-08T14:05:27+00:00","article_modified_time":"2022-02-10T13:39:44+00:00","og_image":[{"width":2480,"height":1653,"url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/02\/7S9A8816.jpg","type":"image\/jpeg"}],"author":"Robin CUVILLIER","twitter_card":"summary_large_image","twitter_description":"one.brussels is voor een fusie van de zes Brusselse politiezones. Maar het voorstel van resolutie dat is voorgelegd, zal dat niet realiseren.","twitter_image":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/02\/7S9A8816.jpg","twitter_misc":{"\u00c9crit par":"Robin CUVILLIER","Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/","url":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/","name":"E\u00e9nmaking van de Brusselse politiezones: waarom we de resolutie van N-VA niet steunen - Els Rochette","isPartOf":{"@id":"https:\/\/www.elsrochette.brussels\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/#primaryimage"},"image":{"@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A8816.jpg","datePublished":"2022-02-08T14:05:27+00:00","dateModified":"2022-02-10T13:39:44+00:00","author":{"@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0"},"description":"one.brussels is voor een fusie van de zes Brusselse politiezones. Maar het voorstel van resolutie dat is voorgelegd, zal dat niet realiseren.","breadcrumb":{"@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/#primaryimage","url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A8816.jpg","contentUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A8816.jpg","width":2480,"height":1653},{"@type":"BreadcrumbList","@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/resolutie-over-fusie-van-de-brusselse-politiezones-waarom-we-ze-niet-steunen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elsrochette.brussels\/"},{"@type":"ListItem","position":2,"name":"E\u00e9nmaking van de Brusselse politiezones: waarom we de resolutie van N-VA niet steunen"}]},{"@type":"WebSite","@id":"https:\/\/www.elsrochette.brussels\/#website","url":"https:\/\/www.elsrochette.brussels\/","name":"Els Rochette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elsrochette.brussels\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0","name":"Robin CUVILLIER"}]}},"_links":{"self":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/1696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/comments?post=1696"}],"version-history":[{"count":14,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/1696\/revisions"}],"predecessor-version":[{"id":1717,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/1696\/revisions\/1717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media\/959"}],"wp:attachment":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media?parent=1696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/categories?post=1696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/tags?post=1696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}