{"id":2329,"date":"2022-06-29T14:53:00","date_gmt":"2022-06-29T14:53:00","guid":{"rendered":"https:\/\/www.elsrochette.brussels\/?p=2329"},"modified":"2022-07-15T09:17:12","modified_gmt":"2022-07-15T09:17:12","slug":"10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen","status":"publish","type":"post","link":"https:\/\/www.elsrochette.brussels\/fr\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/","title":{"rendered":"10 millions suppl\u00e9mentaires pour faire face aux factures d\u2019\u00e9nergie"},"content":{"rendered":"<p><strong>De nombreux Bruxellois souffrent en raison de l'augmentation consid\u00e9rable des factures d'\u00e9nergie. De plus, les prix resteront plus \u00e9lev\u00e9s que ceux de la p\u00e9riode pr\u00e9-corona au moins jusqu'en 2025. Il n'est pas certain qu'ils retombent ensuite. Qui vivra verra.&nbsp;<\/strong><\/p>\n\n\n\n<p>Plus d\u2019un m\u00e9nage bruxellois sur quatre vit en situation de pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique, ce qui repr\u00e9sente plus de 75.000 m\u00e9nages. <\/p>\n\n\n\n<p>Et ce chiffre continuera \u00e0 augmenter. Certainement tant que les prix de l\u2019\u00e9nergie continueront \u00e0 grimper. De plus en plus de personnes de la classe moyenne ont du mal \u00e0 boucler les fins de mois. Un emploi r\u00e9mun\u00e9r\u00e9 n\u2019est pas une garantie suffisante pour pouvoir payer sa facture d\u2019\u00e9nergie.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Des moyens d\u00e9bloqu\u00e9s pour un soutien au paiement des factures d\u2019\u00e9nergie. Il faut maintenant toucher le bon public et veiller \u00e0 ne laisser personne de c\u00f4t\u00e9 pour que cet argent parvienne \u00e0 ceux qui en ont besoin. <\/p><\/blockquote>\n\n\n\n<h1 class=\"wp-block-heading\">Ai-je aussi droit \u00e0 cette aide ?&nbsp;<\/h1>\n\n\n\n<p>Au d\u00e9but de l'ann\u00e9e, le gouvernement bruxellois a annonc\u00e9 qu'il lib\u00e9rerait 10 millions d'euros pour les CPAS de Bruxelles afin de soutenir les Bruxellois pendant la crise \u00e9nerg\u00e9tique. Mais les arr\u00eat\u00e9s d\u2019ex\u00e9cution pr\u00e9cisant le public \u00e9ligible \u00e0 cette aide se font encore attendre. Les CPAS ne savent donc pas \u00e0 quelles personnes ils peuvent verser ces fonds. <a href=\"https:\/\/www.elsrochette.brussels\/fr\/armoede\/nog-geen-duidelijke-regels-voor-wie-recht-heeft-op-hulp-bij-energiefactuur\/\">uitvoeringsbesluiten<\/a>, die afbakenen wie er precies recht heeft op steun uit dit fonds, laten op zich wachten.&nbsp;Daardoor weten OCMW&#8217;s niet aan welke cli\u00ebnten ze het geld mogen geven.<\/p>\n\n\n\n<p>Les arr\u00eat\u00e9s d\u2019ex\u00e9cution seront pr\u00eats avant les vacances d\u2019\u00e9t\u00e9 (soit avant le 21\/7) d\u2019apr\u00e8s la r\u00e9ponse du Ministre Maron \u00e0 <a href=\"https:\/\/www.elsrochette.brussels\/fr\/armoede\/nog-geen-duidelijke-regels-voor-wie-recht-heeft-op-hulp-bij-energiefactuur\/\">la question<\/a>&nbsp;que je lui ai pos\u00e9e aujourd\u2019hui au Parlement bruxellois. <\/p>\n\n\n\n<p>Voil\u00e0 une bonne nouvelle. Avec un cadre clair, les CPAS pourront se mettre \u00e0 l\u2019ouvrage, r\u00e9agir plus rapidement (vu la r\u00e9duction de la charge administrative) et octroyer imm\u00e9diatement une aide \u00e0 ceux qui en ont besoin. <\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Moyens suppl\u00e9mentaires<\/h1>\n\n\n\n<p>Le Gouvernement bruxellois va encore un peu plus loin en lib\u00e9rant 10 millions d'euros suppl\u00e9mentaires pour amortir les cons\u00e9quences sociales de la crise \u00e9nerg\u00e9tique. <\/p>\n\n\n\n<p>C\u2019est une excellente nouvelle. Les CPAS de Bruxelles sont d\u00e9j\u00e0 d\u00e9bord\u00e9s par le nombre croissant de demandes. L'argent est n\u00e9cessaire. Surtout quand on sait que de nouveaux b\u00e9n\u00e9ficiaires n'ont pas encore trouv\u00e9 le chemin des CPAS.  <\/p>\n\n\n\n<h1 class=\"wp-block-heading\">En finir avec les tabous<\/h1>\n\n\n\n<p>De nombreux Bruxellois de la classe moyenne rencontrent des difficult\u00e9s et ont droit au soutien du CPAS. Mais ils ne savent tout simplement pas que le CPAS est l\u00e0 pour eux aussi, maintenant que les prix de l'\u00e9nergie sont si \u00e9lev\u00e9s. Ou ils ont honte d'y aller. <\/p>\n\n\n\n<p>Il faut faire sauter ce tabou.<\/p>\n\n\n\n<p>C'est pourquoi le Ministre a annonc\u00e9 aujourd\u2019hui qu\u2019une grande campagne de sensibilisation est en pr\u00e9paration pour un lancement pr\u00e9vu en septembre. <\/p>\n\n\n\n<p>C'est une autre bonne nouvelle. <\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Conclusion<\/h1>\n\n\n\n<p>Les fonds pour l\u2019aide au paiement des factures d\u2019\u00e9nergie ont \u00e9t\u00e9 lib\u00e9r\u00e9s. <\/p>\n\n\n\n<p>Il faut maintenant toucher le bon public et veiller \u00e0 ne laisser personne de c\u00f4t\u00e9 <\/p>\n\n\n\n<p>pour que cet argent parvienne \u00e0 ceux qui en ont besoin. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">En savoir plus ? <\/h2>\n\n\n\n<p>Lisez cette \u00e9tude r\u00e9cente sur les prix \u00e9lev\u00e9s de l\u2019\u00e9nergie par <a href=\"http:\/\/[1] https:\/\/www.brugel.brussels\/publication\/document\/studies\/2021\/nl\/STUDIE-36-KWALITEITSONDERZOEK-ENERGIEARMOEDE-IN-HET-BHG.pdf\">Brugel<\/a> et les <a href=\"https:\/\/en.calameo.com\/read\/001774295203bf5400243?authid=ZAdmSpSVIQgp\">Fondation Roi Baudouin<\/a><\/p>","protected":false},"excerpt":{"rendered":"Door de enorme stijging van de energiefacturen komen veel Brusselaars in de problemen. Bovendien zullen de prijzen nog minstens tot 2025 hoger blijven dan pre-corona. Of ze nadien weer zakken, is niet zeker. Het blijft koffiedik kijken.&nbsp; Meer dan 1 op 4 van de Brusselse gezinnen leeft in energiearmoede. Dat zijn meer dan 75.000 huishoudens&#8230;. <a class=\"meer\" href=\"https:\/\/www.elsrochette.brussels\/fr\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/\">Lees meer<\/a>","protected":false},"author":1,"featured_media":2257,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-armoede"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10 miljoen extra voor strijd tegen de hoge energiefacturen - Els Rochette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elsrochette.brussels\/fr\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 miljoen extra voor strijd tegen de hoge energiefacturen - Els Rochette\" \/>\n<meta property=\"og:description\" content=\"Eerder dit jaar kondigde de Brusselse regering aan 10 miljoen euro vrij te maken voor de Brusselse OCMW\u2019s, om Brusselaars financieel te steunen tijdens de energiecrisis. Voor het zomerreces (dus voor 21\/7) zullen de uitvoeringsbesluiten klaar zijn. Dan zullen OCMW&#039;s weten aan welke cli\u00ebnten ze geld mogen geven.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elsrochette.brussels\/fr\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/\" \/>\n<meta property=\"og:site_name\" content=\"Els Rochette\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T14:53:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T09:17:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/06\/gas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robin CUVILLIER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Eerder dit jaar kondigde de Brusselse regering aan 10 miljoen euro vrij te maken voor de Brusselse OCMW\u2019s, om Brusselaars financieel te steunen tijdens de energiecrisis. Voor het zomerreces (dus voor 21\/7) zullen de uitvoeringsbesluiten klaar zijn. Dan zullen OCMW&#039;s weten aan welke cli\u00ebnten ze geld mogen geven.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/06\/gas.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robin CUVILLIER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/\",\"url\":\"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/\",\"name\":\"10 miljoen extra voor strijd tegen de hoge energiefacturen - Els Rochette\",\"isPartOf\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/06\/gas.jpg\",\"datePublished\":\"2022-06-29T14:53:00+00:00\",\"dateModified\":\"2022-07-15T09:17:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/#primaryimage\",\"url\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/06\/gas.jpg\",\"contentUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/06\/gas.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elsrochette.brussels\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 miljoen extra voor strijd tegen de hoge energiefacturen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\",\"url\":\"https:\/\/www.elsrochette.brussels\/\",\"name\":\"Els Rochette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elsrochette.brussels\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\",\"name\":\"Robin CUVILLIER\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 miljoen extra voor strijd tegen de hoge energiefacturen - Els Rochette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elsrochette.brussels\/fr\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/","og_locale":"fr_FR","og_type":"article","og_title":"10 miljoen extra voor strijd tegen de hoge energiefacturen - Els Rochette","og_description":"Eerder dit jaar kondigde de Brusselse regering aan 10 miljoen euro vrij te maken voor de Brusselse OCMW\u2019s, om Brusselaars financieel te steunen tijdens de energiecrisis. Voor het zomerreces (dus voor 21\/7) zullen de uitvoeringsbesluiten klaar zijn. Dan zullen OCMW's weten aan welke cli\u00ebnten ze geld mogen geven.","og_url":"https:\/\/www.elsrochette.brussels\/fr\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/","og_site_name":"Els Rochette","article_published_time":"2022-06-29T14:53:00+00:00","article_modified_time":"2022-07-15T09:17:12+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/06\/gas.jpg","type":"image\/jpeg"}],"author":"Robin CUVILLIER","twitter_card":"summary_large_image","twitter_description":"Eerder dit jaar kondigde de Brusselse regering aan 10 miljoen euro vrij te maken voor de Brusselse OCMW\u2019s, om Brusselaars financieel te steunen tijdens de energiecrisis. Voor het zomerreces (dus voor 21\/7) zullen de uitvoeringsbesluiten klaar zijn. Dan zullen OCMW's weten aan welke cli\u00ebnten ze geld mogen geven.","twitter_image":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/06\/gas.jpg","twitter_misc":{"\u00c9crit par":"Robin CUVILLIER","Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/","url":"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/","name":"10 miljoen extra voor strijd tegen de hoge energiefacturen - Els Rochette","isPartOf":{"@id":"https:\/\/www.elsrochette.brussels\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/#primaryimage"},"image":{"@id":"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/06\/gas.jpg","datePublished":"2022-06-29T14:53:00+00:00","dateModified":"2022-07-15T09:17:12+00:00","author":{"@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0"},"breadcrumb":{"@id":"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/#primaryimage","url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/06\/gas.jpg","contentUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/06\/gas.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.elsrochette.brussels\/armoede\/10-miljoen-extra-voor-strijd-tegen-de-hoge-energiefacturen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elsrochette.brussels\/"},{"@type":"ListItem","position":2,"name":"10 miljoen extra voor strijd tegen de hoge energiefacturen"}]},{"@type":"WebSite","@id":"https:\/\/www.elsrochette.brussels\/#website","url":"https:\/\/www.elsrochette.brussels\/","name":"Els Rochette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elsrochette.brussels\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0","name":"Robin CUVILLIER"}]}},"_links":{"self":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/2329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/comments?post=2329"}],"version-history":[{"count":15,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/2329\/revisions"}],"predecessor-version":[{"id":2388,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/2329\/revisions\/2388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media\/2257"}],"wp:attachment":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media?parent=2329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/categories?post=2329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/tags?post=2329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}