{"id":2602,"date":"2022-10-07T10:43:44","date_gmt":"2022-10-07T10:43:44","guid":{"rendered":"https:\/\/www.elsrochette.brussels\/?p=2602"},"modified":"2022-10-10T10:38:22","modified_gmt":"2022-10-10T10:38:22","slug":"hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten","status":"publish","type":"post","link":"https:\/\/www.elsrochette.brussels\/fr\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/","title":{"rendered":"Des mesures porteuses d'espoir pour le secteur des titres-services"},"content":{"rendered":"<p><strong>Le gouvernement bruxellois investit beaucoup d'argent dans le secteur des titres-services. Pas moins d'un quart du budget total pour la cr\u00e9ation d'emplois y est consacr\u00e9. Mais les travailleurs en b\u00e9n\u00e9ficient-ils ?<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qui y travaille ?<\/h3>\n\n\n\n<p>Le secteur des titres-services g\u00e9n\u00e8re beaucoup d'emplois \u00e0 Bruxelles : il y emploie plus de 25.000 personnes. <\/p>\n\n\n\n<p>Pour la grande majorit\u00e9, ce sont des femmes travaillant principalement comme aide-m\u00e9nag\u00e8res. Le travail par le biais des titres-services est plut\u00f4t accessible. Par cons\u00e9quent, ces travailleurs appartiennent souvent \u00e0 un groupe pr\u00e9caire. <\/p>\n\n\n\n<p>Ils ne doivent cependant pas sous-estimer l'importance sociale de leur travail. Ils s'assurent que nos bureaux et nos maisons sont propres. Ils font les courses, le repassage, la cuisine et s'occupent parfois des enfants. \u00c7a fait pas mal de boulot.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ce travail m\u00e9rite une r\u00e9mun\u00e9ration d\u00e9cente. Avec la hausse de l'inflation, des loyers et de l'\u00e9nergie, nous devons veiller \u00e0 ce que ces personnes qui travaillent dur puissent garder la t\u00eate hors de l'eau.<\/p><\/blockquote>\n\n\n\n<p>En outre, dans la pratique, les aide-m\u00e9nag\u00e8res sont souvent insuffisamment soutenues dans leur travail physiquement et psychologiquement exigeant. Les situations simplement dangereuses avec des produits de nettoyage chimiques ou des \u00e9chelles beaucoup trop hautes ne sont pas rares.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Que fait le gouvernement de Bruxelles ?<\/h3>\n\n\n\n<p>L'accord social conclu en juin (en savoir plus <a href=\"https:\/\/www.elsrochette.brussels\/fr\/tewerkstelling\/sociaal-akkoord-verbetert-werkomstandigheden-voor-huishoudhulpen\/?fbclid=IwAR1yWRuQpSL175J3PWOAOc1uq1KjLxh_F_EIOTnz8b1bLdGgHVo6-ij8ixE\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a> ) au niveau f\u00e9d\u00e9ral constitue un grand pas en avant sur ces deux points. Mais cela ne change rien au fait que le gouvernement de Bruxelles dispose \u00e9galement de leviers.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>J'esp\u00e8re que le ministre sera strict, que le contrat standard minimum prendra r\u00e9ellement en compte les conditions de travail des travailleurs domestiques, et une solide s\u00e9lection des entreprises qui veulent utiliser les titres-services.<\/p><\/blockquote>\n\n\n\n<p>Devant la <a href=\"https:\/\/www.youtube.com\/watch?v=-QqBNcp4fPI&amp;list=PLQ3uOzWd9MNxZ4u23HVX6fddY_7SjnPbz&amp;index=2&amp;ab_channel=parlement.brussels\" target=\"_blank\" rel=\"noreferrer noopener\">commission des affaires \u00e9conomiques du mercredi 5 octobre<\/a> , le ministre Bernard Clerfayt a expliqu\u00e9 ses projets. Une ordonnance sera bient\u00f4t publi\u00e9e pour faire avancer les travaux sur les questions suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>L'augmentation du prix des titres-services. Les utilisateurs et les entreprises devront contribuer pour que les salaires des travailleurs domestiques puissent augmenter.<\/li><li>Un contrat type deviendra obligatoire. Autrement dit, les employeurs devront respecter un minimum de conditions de travail.<\/li><li>Crit\u00e8res de reconnaissance des entreprises. Toutes les entreprise ne pourront pas utiliser les titres-services, elles devront d'abord prouver qu'elles sont un employeur s\u00fbr et de qualit\u00e9.<\/li><li>D\u00e9termination des heures n\u00e9cessaires pour un emploi, ce qui \u00e9vitera aux aide-m\u00e9nag\u00e8res d'\u00eatre confront\u00e9es \u00e0 des missions impossibles.<\/li><li>En outre, le ministre a \u00e9galement promis d'examiner la possibilit\u00e9 d'un cong\u00e9 de formation pay\u00e9 pour les personnes travaillant dans le secteur des titres-services. Cela conduira \u00e0 une plus grande \u00e9mancipation des femmes et des hommes employ\u00e9s dans le secteur.<\/li><\/ul>\n\n\n\n<p>Voil\u00e0 de belles promesses. Reste \u00e0 voir pour quels r\u00e9sultats. Ce n'est que lorsque nous verrons le projet d'ordonnance du ministre Clerfayt que nous pourrons porter un v\u00e9ritable jugement sur ses plans.<\/p>\n\n\n\n<p>J'esp\u00e8re que le ministre osera \u00eatre strict. Que le contrat standard minimum prendra r\u00e9ellement en compte la sant\u00e9 et les conditions de travail des travailleurs domestiques. Et que les entreprises qui souhaitent utiliser les titres-services fassent l'objet d'un examen approfondi.<\/p>\n\n\n\n<p>Je suivrai l'affaire au Parlement de Bruxelles.<\/p>","protected":false},"excerpt":{"rendered":"De Brusselse regering investeert erg veel geld in de dienstenchequesector. Maar liefst een kwart van het totale budget om werkgelegenheid te cre\u00ebren gaat er naartoe. Maar hebben de werknemers daar baat bij? Wie werkt er? De dienstenchequesector zorgt voor veel tewerkstelling in Brussel: meer dan 25.000 mensen werken in het Brussels gewest in de sector&#8230;. <a class=\"meer\" href=\"https:\/\/www.elsrochette.brussels\/fr\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/\">Lees meer<\/a>","protected":false},"author":1,"featured_media":968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tewerkstelling"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hoopvolle maatregelen voor de dienstenchequesector - Els Rochette<\/title>\n<meta name=\"description\" content=\"De Brusselse regering investeert erg veel geld in de dienstenchequesector. Maar hebben de werknemers daar baat bij?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elsrochette.brussels\/fr\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoopvolle maatregelen voor de dienstenchequesector - Els Rochette\" \/>\n<meta property=\"og:description\" content=\"De Brusselse regering investeert erg veel geld in de dienstenchequesector. Maar hebben de werknemers daar baat bij?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elsrochette.brussels\/fr\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/\" \/>\n<meta property=\"og:site_name\" content=\"Els Rochette\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-07T10:43:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T10:38:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/07\/clay-banks-cEzMOp5FtV4-unsplash-copy-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"1654\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robin CUVILLIER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"De Brusselse regering investeert erg veel geld in de dienstenchequesector. Maar hebben de werknemers daar baat bij?\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/07\/clay-banks-cEzMOp5FtV4-unsplash-copy-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robin CUVILLIER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/\",\"url\":\"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/\",\"name\":\"Hoopvolle maatregelen voor de dienstenchequesector - Els Rochette\",\"isPartOf\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/07\/clay-banks-cEzMOp5FtV4-unsplash-copy-scaled.jpg\",\"datePublished\":\"2022-10-07T10:43:44+00:00\",\"dateModified\":\"2022-10-10T10:38:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\"},\"description\":\"De Brusselse regering investeert erg veel geld in de dienstenchequesector. Maar hebben de werknemers daar baat bij?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/#primaryimage\",\"url\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/07\/clay-banks-cEzMOp5FtV4-unsplash-copy-scaled.jpg\",\"contentUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/07\/clay-banks-cEzMOp5FtV4-unsplash-copy-scaled.jpg\",\"width\":2480,\"height\":1654},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elsrochette.brussels\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoopvolle maatregelen voor de dienstenchequesector\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\",\"url\":\"https:\/\/www.elsrochette.brussels\/\",\"name\":\"Els Rochette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elsrochette.brussels\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\",\"name\":\"Robin CUVILLIER\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoopvolle maatregelen voor de dienstenchequesector - Els Rochette","description":"De Brusselse regering investeert erg veel geld in de dienstenchequesector. Maar hebben de werknemers daar baat bij?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elsrochette.brussels\/fr\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/","og_locale":"fr_FR","og_type":"article","og_title":"Hoopvolle maatregelen voor de dienstenchequesector - Els Rochette","og_description":"De Brusselse regering investeert erg veel geld in de dienstenchequesector. Maar hebben de werknemers daar baat bij?","og_url":"https:\/\/www.elsrochette.brussels\/fr\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/","og_site_name":"Els Rochette","article_published_time":"2022-10-07T10:43:44+00:00","article_modified_time":"2022-10-10T10:38:22+00:00","og_image":[{"width":2480,"height":1654,"url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/07\/clay-banks-cEzMOp5FtV4-unsplash-copy-scaled.jpg","type":"image\/jpeg"}],"author":"Robin CUVILLIER","twitter_card":"summary_large_image","twitter_description":"De Brusselse regering investeert erg veel geld in de dienstenchequesector. Maar hebben de werknemers daar baat bij?","twitter_image":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/07\/clay-banks-cEzMOp5FtV4-unsplash-copy-scaled.jpg","twitter_misc":{"\u00c9crit par":"Robin CUVILLIER","Dur\u00e9e de lecture est.":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/","url":"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/","name":"Hoopvolle maatregelen voor de dienstenchequesector - Els Rochette","isPartOf":{"@id":"https:\/\/www.elsrochette.brussels\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/#primaryimage"},"image":{"@id":"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/07\/clay-banks-cEzMOp5FtV4-unsplash-copy-scaled.jpg","datePublished":"2022-10-07T10:43:44+00:00","dateModified":"2022-10-10T10:38:22+00:00","author":{"@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0"},"description":"De Brusselse regering investeert erg veel geld in de dienstenchequesector. Maar hebben de werknemers daar baat bij?","breadcrumb":{"@id":"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/#primaryimage","url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/07\/clay-banks-cEzMOp5FtV4-unsplash-copy-scaled.jpg","contentUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/07\/clay-banks-cEzMOp5FtV4-unsplash-copy-scaled.jpg","width":2480,"height":1654},{"@type":"BreadcrumbList","@id":"https:\/\/www.elsrochette.brussels\/tewerkstelling\/hoopvolle-maatregelen-voor-de-dienstenchequesector-maar-het-blijft-afwachten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elsrochette.brussels\/"},{"@type":"ListItem","position":2,"name":"Hoopvolle maatregelen voor de dienstenchequesector"}]},{"@type":"WebSite","@id":"https:\/\/www.elsrochette.brussels\/#website","url":"https:\/\/www.elsrochette.brussels\/","name":"Els Rochette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elsrochette.brussels\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0","name":"Robin CUVILLIER"}]}},"_links":{"self":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/2602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/comments?post=2602"}],"version-history":[{"count":6,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/2602\/revisions"}],"predecessor-version":[{"id":2620,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/2602\/revisions\/2620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media\/968"}],"wp:attachment":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media?parent=2602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/categories?post=2602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/tags?post=2602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}