{"id":2670,"date":"2022-10-20T09:54:00","date_gmt":"2022-10-20T09:54:00","guid":{"rendered":"https:\/\/www.elsrochette.brussels\/?p=2670"},"modified":"2022-10-25T06:21:37","modified_gmt":"2022-10-25T06:21:37","slug":"mensenhandel-bestrijden-hoe","status":"publish","type":"post","link":"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/","title":{"rendered":"Comment lutter contre le trafic d\u2019\u00eatres humains ?"},"content":{"rendered":"<p><strong>Dans le cadre de la Journ\u00e9e europ\u00e9enne de lutte contre la traite des \u00eatres humains (18 octobre), Pag-Asa a organis\u00e9 cette semaine plusieurs projections de films et autres \u00e9v\u00e9nements pour mettre en lumi\u00e8re ce ph\u00e9nom\u00e8ne. J\u2019y \u00e9tais pr\u00e9sente aujourd\u2019hui.&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">De quoi s\u2019agit-il ?<\/h2>\n\n\n\n<p>Par trafic d\u2019\u00eatres humains, il faut comprendre tout acte ayant pour objectif d\u2019exploiter des \u00eatres humains. Il peut s\u2019agir d\u2019exploitation sexuelle ou \u00e9conomique comme de mendicit\u00e9 forc\u00e9e, de  trafic ill\u00e9gal d\u2019organes ou de criminalit\u00e9 forc\u00e9e.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Le travail du sexe et le trafic d\u2019\u00eatres humains ne vont pas n\u00e9cessairement de pair. Mais il convient d\u2019intervenir en cas d\u2019exploitation humaine.<\/p><\/blockquote>\n\n\n\n<p>Selon les estimations du Global Slavery Index, le nombre de victimes de la traite en Belgique s'\u00e9l\u00e8ve \u00e0 23 000. <\/p>\n\n\n\n<p>Seule une fraction d\u2019entre elles sont d\u00e9tect\u00e9es car le personnel sp\u00e9cialis\u00e9 est insuffisant dans la police, l'inspection et la justice. <\/p>\n\n\n\n<p>En outre, les victimes ne parviennent souvent pas \u00e0 joindre les organismes qui peuvent les aider au mieux. Parfois, ce sont les victimes elles-m\u00eames qui font obstacle. <\/p>\n\n\n\n<p>Mais m\u00eame les services de premi\u00e8re ligne ne savent pas toujours comment reconna\u00eetre la traite des \u00eatres humains ou quelles organisations sp\u00e9cifiques aident les victimes. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pag-asa pour Bruxelles<\/h2>\n\n\n\n<p>Pag-asa est l'un des trois refuges l\u00e9galement reconnus pour les victimes de la traite, bas\u00e9s \u00e0 Bruxelles. Chaque ann\u00e9e, ils accompagnent 200 personnes qui ont \u00e9t\u00e9 victimes de la traite des \u00eatres humains. <\/p>\n\n\n\n<p>Pag-asa propose \u00e9galement une formation aux professionnels : quels sont les signes r\u00e9v\u00e9lateurs de la traite des \u00eatres humains, quelles sont les mesures \u00e0 prendre ?<\/p>\n\n\n\n<p>En raison de son contexte international, la r\u00e9gion de Bruxelles compte un nombre disproportionn\u00e9 de victimes de la traite d'\u00eatres humains. C'est \u00e9galement un th\u00e8me pour one.brussels.  <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Les communes et les zones de police de Bruxelles ont leurs propres r\u00e8gles concernant le travail du sexe. Les trafiquants d'\u00eatres humains exploitent commod\u00e9ment les ambigu\u00eft\u00e9s et les contradictions.&nbsp;<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Nous devons d\u00e9battre du travail du sexe<\/h2>\n\n\n\n<p>Ce printemps, plusieurs intervenants sont pass\u00e9s devant la commission des Affaires int\u00e9rieures lors d'auditions sur le travail du sexe, comme la chercheuse Magaly Rodriguez, M. Debuf, premier commissaire de la zone de police de Bruxelles-Nord ou l'organisation Utsopi. C'\u00e9tait instructif.<\/p>\n\n\n\n<p>Je travaille au Parlement de Bruxelles sur <a href=\"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/primeur-in-europa-sekswerk\/\">une r\u00e9solution concernant le travail du sexe<\/a>. <\/p>\n\n\n\n<p>Je sugg\u00e8re de se concentrer sur ce qui fonctionne, de nous d\u00e9faire de nos \u00e9motions et de consid\u00e9rer le travail du sexe d'une mani\u00e8re non stigmatisante. Ceux qui l\u2019exercent volontairement exercent une activit\u00e9 professionnelle. <\/p>\n\n\n\n<p>Mais il existe des risques sp\u00e9cifiques. La s\u00e9curit\u00e9 et l'acc\u00e8s aux soins des travailleurs du sexe doivent \u00eatre am\u00e9lior\u00e9s. <\/p>\n\n\n\n<p>Le travail du sexe et le trafic d\u2019\u00eatres humains ne vont pas n\u00e9cessairement de pair. Mais il convient d\u2019intervenir en cas d\u2019exploitation humaine. Il faut mener ce combat.<\/p>\n\n\n\n<p>Avec une meilleure formation dans les zones de police de Bruxelles, ainsi que plus de ressources pour les organisations comp\u00e9tentes. Mais aussi une harmonisation de la politique en mati\u00e8re de travail du sexe. <\/p>\n\n\n\n<p>Les communes et les zones de police de Bruxelles ont en effet leurs propres r\u00e8gles. Les trafiquants d'\u00eatres humains exploitent commod\u00e9ment ces ambigu\u00eft\u00e9s et ces contradictions.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">C'est ce que fait mon coll\u00e8gue de la Chambre...<\/h2>\n\n\n\n<p>De nombreux leviers dans la lutte contre la traite des \u00eatres humains se situent au niveau f\u00e9d\u00e9ral. Heureusement, cette question a fait l'objet d'une attention accrue au cours des derniers mois. <\/p>\n\n\n\n<p>Ce printemps, mon coll\u00e8gue Ben Segers, d\u00e9put\u00e9 Vooruit \u00e0 la Chambre, a pris l'initiative de cr\u00e9er une commission sp\u00e9ciale sur la traite des \u00eatres humains. Cette commission devrait r\u00e9soudre le manque de personnel et donner plus de poids \u00e0 la lutte contre la traite des \u00eatres humains.&nbsp;<\/p>\n\n\n\n<p>Et c'est n\u00e9cessaire. Cet \u00e9t\u00e9 encore, la r\u00e9v\u00e9lation d'abus cruels dans un chantier de Borealis a suscit\u00e9 un vif \u00e9moi.<\/p>\n\n\n\n<p>one.brussels-Vooruit prend \u00e9galement cette question \u00e0 c\u0153ur. Parce que l'exploitation existe encore. Et nous ne devrions pas accepter cela.<\/p>\n\n\n\n<p>Image : Je suis all\u00e9e voir le film Tori et Lokita et j'ai assist\u00e9 \u00e0 la discussion apr\u00e8s la soir\u00e9e avec Pag-asa, le jeudi 20 octobre au Cinema Palace.<\/p>","protected":false},"excerpt":{"rendered":"In het kader van de Europese dag tegen mensenhandel (18 oktober) organiseerde Pag-Asa deze week verschillende filmvertoningen en andere evenementen om mensenhandel onder de aandacht te brengen. Ik was erbij vandaag.&nbsp; Waarover gaat het? Onder mensenhandel verstaan we elke handeling die tot doel heeft mensen uit te buiten. Het kan gaan over economische en seksuele&#8230; <a class=\"meer\" href=\"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/\">Lees meer<\/a>","protected":false},"author":1,"featured_media":2671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,17,9],"tags":[],"class_list":["post-2670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-armoede","category-pact-voor-brussel","category-tewerkstelling"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mensenhandel bestrijden: hoe? - Els Rochette<\/title>\n<meta name=\"description\" content=\"Sekswerk en mensenhandel zijn niet per definitie aan elkaar gekoppeld. Maar als mensen worden uitgebuit, dan is optreden nodig. Ik werk aan een resolutie over sekswerk.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mensenhandel bestrijden: hoe? - Els Rochette\" \/>\n<meta property=\"og:description\" content=\"Sekswerk en mensenhandel zijn niet per definitie aan elkaar gekoppeld. Maar als mensen worden uitgebuit, dan is optreden nodig. Ik werk aan een resolutie over sekswerk.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/\" \/>\n<meta property=\"og:site_name\" content=\"Els Rochette\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-20T09:54:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-25T06:21:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/10\/e6da1a4b-09bb-4985-a0d9-4e52e7ec366c-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robin CUVILLIER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Sekswerk en mensenhandel zijn niet per definitie aan elkaar gekoppeld. Maar als mensen worden uitgebuit, dan is optreden nodig. Ik werk aan een resolutie over sekswerk.\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robin CUVILLIER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/\",\"url\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/\",\"name\":\"Mensenhandel bestrijden: hoe? - Els Rochette\",\"isPartOf\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/10\/e6da1a4b-09bb-4985-a0d9-4e52e7ec366c-2.jpg\",\"datePublished\":\"2022-10-20T09:54:00+00:00\",\"dateModified\":\"2022-10-25T06:21:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\"},\"description\":\"Sekswerk en mensenhandel zijn niet per definitie aan elkaar gekoppeld. Maar als mensen worden uitgebuit, dan is optreden nodig. Ik werk aan een resolutie over sekswerk.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/#primaryimage\",\"url\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/10\/e6da1a4b-09bb-4985-a0d9-4e52e7ec366c-2.jpg\",\"contentUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/10\/e6da1a4b-09bb-4985-a0d9-4e52e7ec366c-2.jpg\",\"width\":1536,\"height\":2048,\"caption\":\"vertoning Tori en Lokita met Pagasa 20-10\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elsrochette.brussels\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensenhandel bestrijden: hoe?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\",\"url\":\"https:\/\/www.elsrochette.brussels\/\",\"name\":\"Els Rochette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elsrochette.brussels\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\",\"name\":\"Robin CUVILLIER\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mensenhandel bestrijden: hoe? - Els Rochette","description":"Sekswerk en mensenhandel zijn niet per definitie aan elkaar gekoppeld. Maar als mensen worden uitgebuit, dan is optreden nodig. Ik werk aan een resolutie over sekswerk.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/","og_locale":"fr_FR","og_type":"article","og_title":"Mensenhandel bestrijden: hoe? - Els Rochette","og_description":"Sekswerk en mensenhandel zijn niet per definitie aan elkaar gekoppeld. Maar als mensen worden uitgebuit, dan is optreden nodig. Ik werk aan een resolutie over sekswerk.","og_url":"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/","og_site_name":"Els Rochette","article_published_time":"2022-10-20T09:54:00+00:00","article_modified_time":"2022-10-25T06:21:37+00:00","og_image":[{"width":1536,"height":2048,"url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/10\/e6da1a4b-09bb-4985-a0d9-4e52e7ec366c-2.jpg","type":"image\/jpeg"}],"author":"Robin CUVILLIER","twitter_card":"summary_large_image","twitter_description":"Sekswerk en mensenhandel zijn niet per definitie aan elkaar gekoppeld. Maar als mensen worden uitgebuit, dan is optreden nodig. Ik werk aan een resolutie over sekswerk.","twitter_misc":{"\u00c9crit par":"Robin CUVILLIER","Dur\u00e9e de lecture est.":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/","url":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/","name":"Mensenhandel bestrijden: hoe? - Els Rochette","isPartOf":{"@id":"https:\/\/www.elsrochette.brussels\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/#primaryimage"},"image":{"@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/10\/e6da1a4b-09bb-4985-a0d9-4e52e7ec366c-2.jpg","datePublished":"2022-10-20T09:54:00+00:00","dateModified":"2022-10-25T06:21:37+00:00","author":{"@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0"},"description":"Sekswerk en mensenhandel zijn niet per definitie aan elkaar gekoppeld. Maar als mensen worden uitgebuit, dan is optreden nodig. Ik werk aan een resolutie over sekswerk.","breadcrumb":{"@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/#primaryimage","url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/10\/e6da1a4b-09bb-4985-a0d9-4e52e7ec366c-2.jpg","contentUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2022\/10\/e6da1a4b-09bb-4985-a0d9-4e52e7ec366c-2.jpg","width":1536,"height":2048,"caption":"vertoning Tori en Lokita met Pagasa 20-10"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elsrochette.brussels\/pact-voor-brussel\/mensenhandel-bestrijden-hoe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elsrochette.brussels\/"},{"@type":"ListItem","position":2,"name":"Mensenhandel bestrijden: hoe?"}]},{"@type":"WebSite","@id":"https:\/\/www.elsrochette.brussels\/#website","url":"https:\/\/www.elsrochette.brussels\/","name":"Els Rochette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elsrochette.brussels\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0","name":"Robin CUVILLIER"}]}},"_links":{"self":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/2670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/comments?post=2670"}],"version-history":[{"count":20,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/2670\/revisions"}],"predecessor-version":[{"id":2723,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/2670\/revisions\/2723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media\/2671"}],"wp:attachment":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media?parent=2670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/categories?post=2670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/tags?post=2670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}