{"id":335,"date":"2021-05-17T10:20:38","date_gmt":"2021-05-17T10:20:38","guid":{"rendered":"https:\/\/www.dev.elsrochette.brussels\/?p=335"},"modified":"2021-06-02T10:16:50","modified_gmt":"2021-06-02T10:16:50","slug":"gespierd-politieoptreden-op-la-boum-ii","status":"publish","type":"post","link":"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/","title":{"rendered":"Interventions polici\u00e8res muscl\u00e9es \u00e0 La Boum II, dans le calme le 8 mai : quels enseignements ?"},"content":{"rendered":"<p>Le 8 mai \u00e9tait le premier soir des assouplissements et la suppression du couvre-feu. Une grande f\u00eate a eu lieu place Sainte-Croix, \u00e0 Ixelles, en violation de l\u2019interdiction de rassemblement (\u00e0 partir de 22h). La police est parvenue \u00e0 disperser les f\u00eatards dans le calme alors qu\u2019une semaine plus t\u00f4t, des bless\u00e9s ont \u00e9t\u00e9 \u00e0 d\u00e9plorer lors de La Boum II, en raison d\u2019une intervention excessive de la police. <\/p>\n\n\n\n<p>Comment l\u2019expliquer ? Il est essentiel de bien analyser ces \u00e9v\u00e9nements. Car il y aura tr\u00e8s probablement de nouveaux rassemblements dans les prochains mois. Nous devons nous y pr\u00e9parer. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Il n\u2019est jamais \u00e9vident de contr\u00f4ler une foule. Mais des erreurs ont \u00e9t\u00e9 commises lors l\u2019intervention polici\u00e8re \u00e0 La Boum II : asperger de gaz lacrymog\u00e8ne \u00e0 bout portant, pi\u00e9tiner quelqu\u2019un qui se trouve \u00e0 terre ou foncer sur les pelouses noires de monde avec les canons \u00e0 eau.<\/p><\/blockquote>\n\n\n\n<p>Tout le monde peut comprendre qu\u2019il est difficile de garder une foule sous contr\u00f4le. Mais cela ne peut pas servir d\u2019excuse pour asperger d\u00e9lib\u00e9r\u00e9ment de gaz lacrymog\u00e8ne dans les yeux et \u00e0 bout portant, pour pi\u00e9tiner ou foncer sur les pelouses noires de monde avec des canons \u00e0 eau. Comme c\u2019est arriv\u00e9 \u00e0 La Boum II au Bois de la Cambre. De nombreux citoyens innocents ont \u00e9t\u00e9 arr\u00eat\u00e9s avec brutalit\u00e9. Il aurait \u00e9t\u00e9 possible de s\u2019y prendre autrement.<\/p>\n\n\n\n<p>Ook <a href=\"https:\/\/www.facebook.com\/kairospresse\/videos\/829766097637389\">Un expert de s\u00e9curit\u00e9 pr\u00e9sent sur place<\/a>a \u00e9galement formul\u00e9 des reproches. Il aurait \u00e9t\u00e9 facile de s\u00e9parer les \u00e9meutiers de la grande masse des personnes pacifiques. Les \u00e9meutiers ne constituaient qu'un groupe relativement restreint : une trentaine de jeunes, tous habill\u00e9s de noir, beaucoup portant des gants noirs, une casquette et un masque. Leur comportement indiquait clairement qu\u2019ils \u00e9taient venus avec de mauvaises intentions. Il y avait un autre groupe d\u2019\u00e9meutiers, constitu\u00e9 de hooligans. Il \u00e9tait \u00e9vident qu\u2019eux aussi avaient l\u2019intention d\u2019une confrontation violente avec la police. C\u2019est d\u2019ailleurs ce qu\u2019indiquent de nombreux t\u00e9moignages et images diffus\u00e9s sur les r\u00e9seaux sociaux. Pourquoi la police a-t-elle laiss\u00e9 faire ces deux petits groupes agressifs ? Pourquoi n\u2019est-elle pas intervenue plus t\u00f4t ? Pourquoi avoir par contre charg\u00e9 par la suite ? <\/p>\n\n\n\n<p>Qui \u00e9tait en charge de la r\u00e9ponse polici\u00e8re ? Qui a d\u00e9cid\u00e9 d\u2019intervenir ? Comment allons-nous faire respecter l\u2019interdiction de rassemblement \u00e0 Bruxelles \u00e0 l'avenir ? Voil\u00e0 les questions que je pose au Ministre-Pr\u00e9sident. Car nous devons \u00e9viter la surench\u00e8re dans la violence, en toutes circonstances.<\/p>","protected":false},"excerpt":{"rendered":"8 mei was de eerste avond van de versoepelingen en de afschaffing van de avondklok. Op een groot feest op het Heilig Kruisplein in Elsene werd het samenscholingsverbod (vanaf 22 uur) overtreden. De politie dreef de feestvierders uiteen, zonder geweld. Een week eerder, tijdens La Boum II, vielen er gewonden door het buitensporige optreden van&#8230; <a class=\"meer\" href=\"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/\">Lees meer<\/a>","protected":false},"author":1,"featured_media":530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veiligheid"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gespierd politieoptreden op La Boum II, kalm op 8 mei: welke lessen? - Els Rochette<\/title>\n<meta name=\"description\" content=\"Op La Boum II gebruikte de politie veel geweld. Een week later op het Flageyplein was het rustig. Hoe gaat Brussel in de toekomst het samenscholingsverbod handhaven?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gespierd politieoptreden op La Boum II, kalm op 8 mei: welke lessen? - Els Rochette\" \/>\n<meta property=\"og:description\" content=\"Op La Boum II gebruikte de politie veel geweld. Een week later op het Flageyplein was het rustig. Hoe gaat Brussel in de toekomst het samenscholingsverbod handhaven?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"Els Rochette\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-17T10:20:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-02T10:16:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A4016.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"1653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robin CUVILLIER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robin CUVILLIER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/\",\"url\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/\",\"name\":\"Gespierd politieoptreden op La Boum II, kalm op 8 mei: welke lessen? - Els Rochette\",\"isPartOf\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A4016.jpg\",\"datePublished\":\"2021-05-17T10:20:38+00:00\",\"dateModified\":\"2021-06-02T10:16:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\"},\"description\":\"Op La Boum II gebruikte de politie veel geweld. Een week later op het Flageyplein was het rustig. Hoe gaat Brussel in de toekomst het samenscholingsverbod handhaven?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/#primaryimage\",\"url\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A4016.jpg\",\"contentUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A4016.jpg\",\"width\":2480,\"height\":1653,\"caption\":\"Manifestatie n.a.v. overlijden Ibrahima 24\/1\/2021 (door Robin Cuvillier)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elsrochette.brussels\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gespierd politieoptreden op La Boum II, kalm op 8 mei: welke lessen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\",\"url\":\"https:\/\/www.elsrochette.brussels\/\",\"name\":\"Els Rochette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elsrochette.brussels\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\",\"name\":\"Robin CUVILLIER\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gespierd politieoptreden op La Boum II, kalm op 8 mei: welke lessen? - Els Rochette","description":"Op La Boum II gebruikte de politie veel geweld. Een week later op het Flageyplein was het rustig. Hoe gaat Brussel in de toekomst het samenscholingsverbod handhaven?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/","og_locale":"fr_FR","og_type":"article","og_title":"Gespierd politieoptreden op La Boum II, kalm op 8 mei: welke lessen? - Els Rochette","og_description":"Op La Boum II gebruikte de politie veel geweld. Een week later op het Flageyplein was het rustig. Hoe gaat Brussel in de toekomst het samenscholingsverbod handhaven?","og_url":"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/","og_site_name":"Els Rochette","article_published_time":"2021-05-17T10:20:38+00:00","article_modified_time":"2021-06-02T10:16:50+00:00","og_image":[{"width":2480,"height":1653,"url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A4016.jpg","type":"image\/jpeg"}],"author":"Robin CUVILLIER","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Robin CUVILLIER","Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/","url":"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/","name":"Gespierd politieoptreden op La Boum II, kalm op 8 mei: welke lessen? - Els Rochette","isPartOf":{"@id":"https:\/\/www.elsrochette.brussels\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/#primaryimage"},"image":{"@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A4016.jpg","datePublished":"2021-05-17T10:20:38+00:00","dateModified":"2021-06-02T10:16:50+00:00","author":{"@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0"},"description":"Op La Boum II gebruikte de politie veel geweld. Een week later op het Flageyplein was het rustig. Hoe gaat Brussel in de toekomst het samenscholingsverbod handhaven?","breadcrumb":{"@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/#primaryimage","url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A4016.jpg","contentUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2021\/05\/7S9A4016.jpg","width":2480,"height":1653,"caption":"Manifestatie n.a.v. overlijden Ibrahima 24\/1\/2021 (door Robin Cuvillier)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/gespierd-politieoptreden-op-la-boum-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elsrochette.brussels\/"},{"@type":"ListItem","position":2,"name":"Gespierd politieoptreden op La Boum II, kalm op 8 mei: welke lessen?"}]},{"@type":"WebSite","@id":"https:\/\/www.elsrochette.brussels\/#website","url":"https:\/\/www.elsrochette.brussels\/","name":"Els Rochette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elsrochette.brussels\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0","name":"Robin CUVILLIER"}]}},"_links":{"self":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/comments?post=335"}],"version-history":[{"count":9,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/335\/revisions"}],"predecessor-version":[{"id":350,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/335\/revisions\/350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media\/530"}],"wp:attachment":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media?parent=335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/categories?post=335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/tags?post=335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}