{"id":3508,"date":"2023-05-24T09:08:29","date_gmt":"2023-05-24T09:08:29","guid":{"rendered":"https:\/\/www.elsrochette.brussels\/?p=3508"},"modified":"2023-06-01T10:10:01","modified_gmt":"2023-06-01T10:10:01","slug":"publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij","status":"publish","type":"post","link":"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/","title":{"rendered":"\u00c9v\u00e9nement public projet de dialogue entre jeunes et police"},"content":{"rendered":"<p><strong>Un projet innovant, dans le but d\u2019am\u00e9liorer les relations entre les jeunes et la police dans la zone de police Midi a d\u00e9marr\u00e9 en 2021 \u00e0 l\u2019initiative de Pascal Smet, <strong>membre du Coll\u00e8ge de la VGC en charge de la Jeunesse.<\/strong><\/strong>.<\/p>\n\n\n\n<p>La police et les jeunes Bruxellois ont fr\u00e9quemment des accrochages. La m\u00e9fiance est r\u00e9ciproque. <\/p>\n\n\n\n<p>Pascal Smet a subsidi\u00e9 un projet de dialogue visant \u00e0 am\u00e9liorer leurs relations. Un \u00e9v\u00e9nement public au j\u2019\u00e9tais pr\u00e9sente a \u00e9t\u00e9 organis\u00e9 aujourd\u2019hui \u00e0 ce sujet.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Des travailleurs de jeunesse et des agents de police ont t\u00e9moign\u00e9 : la confiance est plus grande entre eux. Mais les nombreux contr\u00f4les d\u2019identit\u00e9 restent une source de frustration. Et le dialogue seul ne permettra pas de r\u00e9soudre le probl\u00e8me.\u00a0<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Pistes et partenaires<\/h2>\n\n\n\n<p>Plusieurs pistes d\u2019am\u00e9lioration sont \u00e9tudi\u00e9es. <\/p>\n\n\n\n<p>Travailler \u00e0 une image positive des jeunes, de la police et des travailleurs de jeunesse.<\/p>\n\n\n\n<p>Renforcer les connaissances et comp\u00e9tences de la police dans leurs rapports avec les jeunes.<\/p>\n\n\n\n<p>Informer les jeunes de leurs droits et de leurs devoirs envers la police.<\/p>\n\n\n\n<p>Int\u00e9grer la perspective des jeunes dans la politique de police locale.<\/p>\n\n\n\n<p> Plusieurs partenaires \u00e9taient donc pr\u00e9sents, chacun avec leur propres expertises et comp\u00e9tences : l\u2019organisation de jeunesse JES, la zone de police Midi et les communes de Saint-Gilles, Forest et Anderlecht, la VGC et son Conseil de la Jeunesse ainsi que l\u2019agence de s\u00e9curit\u00e9 de Bruxelles, safe.brussels. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confiance<\/h2>\n\n\n\n<p>Les travailleurs de jeunesse et les policiers ont t\u00e9moign\u00e9 d\u2019une \u00e9volution positive de la situation lors de l\u2019\u00e9v\u00e9nement public. La confiance s'est renforc\u00e9e. <\/p>\n\n\n\n<p>Ce bon sentiment est un d\u00e9but. <\/p>\n\n\n\n<p>Mais les contr\u00f4les d'identit\u00e9 fr\u00e9quents restent une source de frustration comme cela a \u00e9t\u00e9 confirm\u00e9 une nouvelle fois. Le dialogue seul ne suffira pas \u00e0 r\u00e9soudre ce probl\u00e8me.\u00a0<\/p>\n\n\n\n<p>Les pratiques doivent parfois simplement changer, avec des proc\u00e9dures polici\u00e8res diff\u00e9rentes. Seulement, la R\u00e9gion bruxelloise n'a pas la main \u00e0 ce sujet. C'est la ministre de l'Int\u00e9rieur qui d\u00e9termine ces proc\u00e9dures, en collaboration avec les communes.<\/p>\n\n\n\n<p>La R\u00e9gion bruxelloise peut en revanche peser sur la formation continue des policiers. Plus de formation aux dilemmes \u00e9thiques, pour mieux approcher les jeunes...<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pour la suite<\/h2>\n\n\n\n<p>J'ai trouv\u00e9 l'expos\u00e9 pendant l\u2019\u00e9v\u00e9nement public tr\u00e8s convaincant. On a beaucoup appris sur la mani\u00e8re de mettre en place un tel projet de dialogue.  <\/p>\n\n\n\n<p>J'esp\u00e8re que ce projet aura une suite.<\/p>\n\n\n\n<p>Y aura-t-il un suivi de la part de la R\u00e9gion, avec un d\u00e9ploiement dans d'autres zones de police ? Que fait la R\u00e9gion en termes de formation compl\u00e9mentaire ?<\/p>\n\n\n\n<p>J'ai pos\u00e9 une question au Ministre-Pr\u00e9sident. <\/p>","protected":false},"excerpt":{"rendered":"In 2021 startte een vernieuwend project om de relatie tussen jongeren en de politie in de politiezone Zuid te verbeteren, op initiatief van Pascal Smet, VGC-collegelid bevoegd voor jeugd. Politie en Brusselse jongeren botsen vaak met elkaar. Ze vertrouwen elkaar niet. Pascal Smet subsidieerde een dialoogproject om de relatie politie-jongeren te verbeteren. Daarover was er&#8230; <a class=\"meer\" href=\"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/\">Lees meer<\/a>","protected":false},"author":1,"featured_media":3484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veiligheid"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Publieksmoment dialoogproject jongeren-politie - Els Rochette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Publieksmoment dialoogproject jongeren-politie - Els Rochette\" \/>\n<meta property=\"og:description\" content=\"In 2021 startte een vernieuwend project om de relatie tussen jongeren en de politie in de politiezone Zuid te verbeteren, op initiatief van Pascal Smet, VGC-collegelid bevoegd voor jeugd. Politie en Brusselse jongeren botsen vaak met elkaar. Ze vertrouwen elkaar niet. Pascal Smet subsidieerde een dialoogproject om de relatie politie-jongeren te verbeteren. Daarover was er... Lees meer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/\" \/>\n<meta property=\"og:site_name\" content=\"Els Rochette\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-24T09:08:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-01T10:10:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/05\/40717983-4397-49e8-8f91-391bfb01eb67.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robin CUVILLIER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robin CUVILLIER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/\",\"url\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/\",\"name\":\"Publieksmoment dialoogproject jongeren-politie - Els Rochette\",\"isPartOf\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/05\/40717983-4397-49e8-8f91-391bfb01eb67.jpg\",\"datePublished\":\"2023-05-24T09:08:29+00:00\",\"dateModified\":\"2023-06-01T10:10:01+00:00\",\"author\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/#primaryimage\",\"url\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/05\/40717983-4397-49e8-8f91-391bfb01eb67.jpg\",\"contentUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/05\/40717983-4397-49e8-8f91-391bfb01eb67.jpg\",\"width\":2016,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elsrochette.brussels\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publieksmoment dialoogproject jongeren-politie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\",\"url\":\"https:\/\/www.elsrochette.brussels\/\",\"name\":\"Els Rochette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elsrochette.brussels\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\",\"name\":\"Robin CUVILLIER\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Publieksmoment dialoogproject jongeren-politie - Els Rochette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/","og_locale":"fr_FR","og_type":"article","og_title":"Publieksmoment dialoogproject jongeren-politie - Els Rochette","og_description":"In 2021 startte een vernieuwend project om de relatie tussen jongeren en de politie in de politiezone Zuid te verbeteren, op initiatief van Pascal Smet, VGC-collegelid bevoegd voor jeugd. Politie en Brusselse jongeren botsen vaak met elkaar. Ze vertrouwen elkaar niet. Pascal Smet subsidieerde een dialoogproject om de relatie politie-jongeren te verbeteren. Daarover was er... Lees meer","og_url":"https:\/\/www.elsrochette.brussels\/fr\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/","og_site_name":"Els Rochette","article_published_time":"2023-05-24T09:08:29+00:00","article_modified_time":"2023-06-01T10:10:01+00:00","og_image":[{"width":2016,"height":1512,"url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/05\/40717983-4397-49e8-8f91-391bfb01eb67.jpg","type":"image\/jpeg"}],"author":"Robin CUVILLIER","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Robin CUVILLIER","Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/","url":"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/","name":"Publieksmoment dialoogproject jongeren-politie - Els Rochette","isPartOf":{"@id":"https:\/\/www.elsrochette.brussels\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/#primaryimage"},"image":{"@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/05\/40717983-4397-49e8-8f91-391bfb01eb67.jpg","datePublished":"2023-05-24T09:08:29+00:00","dateModified":"2023-06-01T10:10:01+00:00","author":{"@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0"},"breadcrumb":{"@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/#primaryimage","url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/05\/40717983-4397-49e8-8f91-391bfb01eb67.jpg","contentUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/05\/40717983-4397-49e8-8f91-391bfb01eb67.jpg","width":2016,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/publieksmoment-van-het-dialoogproject-jongeren-politie-ik-was-erbij\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elsrochette.brussels\/"},{"@type":"ListItem","position":2,"name":"Publieksmoment dialoogproject jongeren-politie"}]},{"@type":"WebSite","@id":"https:\/\/www.elsrochette.brussels\/#website","url":"https:\/\/www.elsrochette.brussels\/","name":"Els Rochette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elsrochette.brussels\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0","name":"Robin CUVILLIER"}]}},"_links":{"self":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/3508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/comments?post=3508"}],"version-history":[{"count":8,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/3508\/revisions"}],"predecessor-version":[{"id":3521,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/3508\/revisions\/3521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media\/3484"}],"wp:attachment":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media?parent=3508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/categories?post=3508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/tags?post=3508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}