{"id":3827,"date":"2023-08-25T08:30:56","date_gmt":"2023-08-25T08:30:56","guid":{"rendered":"https:\/\/www.elsrochette.brussels\/?p=3827"},"modified":"2023-08-25T08:54:14","modified_gmt":"2023-08-25T08:54:14","slug":"veiligheidsproblematiek-is-ook-gezondheidsprobleem","status":"publish","type":"post","link":"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/","title":{"rendered":"Les nuisances li\u00e9es \u00e0 la drogue \u00e0 Bruxelles-Midi sont aussi un probl\u00e8me de sant\u00e9"},"content":{"rendered":"<p><strong>Les nuisances li\u00e9es \u00e0 la drogue \u00e0 Bruxelles-Midi sont devenues tr\u00e8s importantes. Plusieurs partis politiques souhaitent que la commission des Affaires int\u00e9rieures du Parlement bruxellois se r\u00e9unisse avant la fin des vacances d\u2019\u00e9t\u00e9. Je demande que la Commission de la sant\u00e9 et de l\u2019aide aux personnes se r\u00e9unisse \u00e9galement plus t\u00f4t.&nbsp; <\/strong><\/p>\n\n\n\n<p>Les comit\u00e9s et associations de quartier ont \u00e9t\u00e9 les premiers \u00e0 tirer la sonnette d'alarme sur la situation \u00e0 Bruxelles-Midi. Dans leur quartier, on constate une augmentation de la violence, des vols, de l\u2019usage de drogues, des d\u00e9chets. Enfin, Mme Dutordoir, directrice de la SNCB, a \u00e9galement lanc\u00e9 un appel \u00e0 l\u2019aide. La SNCB ne peut pas faire face au probl\u00e8me de Bruxelles-Midi. <\/p>\n\n\n\n<p>La situation est pr\u00e9occupante. Je comprends les riverains. Chacun a droit \u00e0 une ville s\u00fbre et propre. <\/p>\n\n\n\n<p>Aujourd'hui, l'accent est surtout mis sur la s\u00e9curit\u00e9 et la r\u00e9pression. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La r\u00e9pression est n\u00e9cessaire, mais il ne faut pas oublier que la toxicomanie est avant tout un probl\u00e8me de sant\u00e9.<\/p>\n<\/blockquote>\n\n\n\n<p>Mais il faut aussi se pencher sur les causes. Un probl\u00e8me social et de sant\u00e9 est \u00e0 l\u2019origine. C'est pourquoi j\u2019estime que la commission des Affaires int\u00e9rieures (qui examine la question de la s\u00e9curit\u00e9) ne devrait pas \u00eatre la seule \u00e0 se r\u00e9unir. La Commission de la sant\u00e9 et de l\u2019aide aux personnes devrait \u00e9galement se r\u00e9unir.<\/p>\n\n\n\n<p>Les mesures de s\u00e9curit\u00e9 urgentes \u00e0 elles seules ne seront pas suffisantes. On a \u00e9galement besoin de mesures structurelles, telles que des accueils en suffisance pour les personnes sans-abri et sans domicile et un aide accessible aux toxicomanes. Ces solutions ont un impact \u00e0 long terme. <\/p>\n\n\n\n<p>Il existe d\u00e9j\u00e0 <a href=\"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/brusselse-regering-neemt-actie-tegen-drugsproblematiek\/\">de nouveaux projets<\/a> visant \u00e0 accompagner les toxicomanes et \u00e0 lutter contre les nuisances dans les gares. Quels sont les r\u00e9sultats ? O\u00f9 en est la deuxi\u00e8me salle de consommation de drogues dans le quartier Ribaucourt ou Yser-quartier Nord? Quand ouvrira-t-elle?&nbsp;<\/p>\n\n\n\n<p>Autant de raisons pour une r\u00e9union anticip\u00e9e de la commission.&nbsp;<\/p>\n\n\n\n<p>Dans toute cette agitation, n'oublions pas que la toxicomanie est avant tout un probl\u00e8me de sant\u00e9.<\/p>\n\n\n\n<p>Lisez \u00e9galement mon <a href=\"https:\/\/press.one.brussels\/open-brief-drugsoverlast-onebrussels-vooruit-vraagt-extra-commissie-gezondheid-in-brussels-parlement\">communiqu\u00e9 de presse<\/a> et mon message pr\u00e9c\u00e9dent sur <a href=\"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/brusselse-regering-neemt-actie-tegen-drugsproblematiek\/\">les nouveaux projets de lutte contre la drogue<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"De drugsoverlast aan Brussel-Zuid is erg groot geworden. Een aantal politieke partijen wil dat commissie Binnenlandse Zaken in het Brussels Parlement voor het eind van het zomerreces bijeenkomt. Ik vraag dat ook de Commissie Gezondheid en Bijstand aan Personen vroeger bijeenkomt.&nbsp; Buurtcomit\u00e9s en verenigingen trokken het eerst aan de alarmbel over de situatie aan Brussel-Zuid&#8230;. <a class=\"meer\" href=\"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/\">Lees meer<\/a>","protected":false},"author":1,"featured_media":3834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,1,5],"tags":[],"class_list":["post-3827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-huisvesting-thuislozen","category-mobiliteit-publieke-ruimte","category-veiligheid"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Drugsoverlast aan Brussel-Zuid is ook een gezondheidsprobleem - Els Rochette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drugsoverlast aan Brussel-Zuid is ook een gezondheidsprobleem - Els Rochette\" \/>\n<meta property=\"og:description\" content=\"De drugsoverlast aan Brussel-Zuid is erg groot geworden. Een aantal politieke partijen wil dat commissie Binnenlandse Zaken in het Brussels Parlement voor het eind van het zomerreces bijeenkomt. Ik vraag dat ook de Commissie Gezondheid en Bijstand aan Personen vroeger bijeenkomt.&nbsp; Buurtcomit\u00e9s en verenigingen trokken het eerst aan de alarmbel over de situatie aan Brussel-Zuid.... Lees meer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/\" \/>\n<meta property=\"og:site_name\" content=\"Els Rochette\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-25T08:30:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T08:54:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/08\/auto-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1108\" \/>\n\t<meta property=\"og:image:height\" content=\"739\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robin CUVILLIER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robin CUVILLIER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/\",\"url\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/\",\"name\":\"Drugsoverlast aan Brussel-Zuid is ook een gezondheidsprobleem - Els Rochette\",\"isPartOf\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/08\/auto-1.jpeg\",\"datePublished\":\"2023-08-25T08:30:56+00:00\",\"dateModified\":\"2023-08-25T08:54:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/#primaryimage\",\"url\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/08\/auto-1.jpeg\",\"contentUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/08\/auto-1.jpeg\",\"width\":1108,\"height\":739},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elsrochette.brussels\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drugsoverlast aan Brussel-Zuid is ook een gezondheidsprobleem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\",\"url\":\"https:\/\/www.elsrochette.brussels\/\",\"name\":\"Els Rochette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elsrochette.brussels\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\",\"name\":\"Robin CUVILLIER\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drugsoverlast aan Brussel-Zuid is ook een gezondheidsprobleem - Els Rochette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/","og_locale":"fr_FR","og_type":"article","og_title":"Drugsoverlast aan Brussel-Zuid is ook een gezondheidsprobleem - Els Rochette","og_description":"De drugsoverlast aan Brussel-Zuid is erg groot geworden. Een aantal politieke partijen wil dat commissie Binnenlandse Zaken in het Brussels Parlement voor het eind van het zomerreces bijeenkomt. Ik vraag dat ook de Commissie Gezondheid en Bijstand aan Personen vroeger bijeenkomt.&nbsp; Buurtcomit\u00e9s en verenigingen trokken het eerst aan de alarmbel over de situatie aan Brussel-Zuid.... Lees meer","og_url":"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/","og_site_name":"Els Rochette","article_published_time":"2023-08-25T08:30:56+00:00","article_modified_time":"2023-08-25T08:54:14+00:00","og_image":[{"width":1108,"height":739,"url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/08\/auto-1.jpeg","type":"image\/jpeg"}],"author":"Robin CUVILLIER","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Robin CUVILLIER","Dur\u00e9e de lecture est.":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/","url":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/","name":"Drugsoverlast aan Brussel-Zuid is ook een gezondheidsprobleem - Els Rochette","isPartOf":{"@id":"https:\/\/www.elsrochette.brussels\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/#primaryimage"},"image":{"@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/08\/auto-1.jpeg","datePublished":"2023-08-25T08:30:56+00:00","dateModified":"2023-08-25T08:54:14+00:00","author":{"@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0"},"breadcrumb":{"@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/#primaryimage","url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/08\/auto-1.jpeg","contentUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2023\/08\/auto-1.jpeg","width":1108,"height":739},{"@type":"BreadcrumbList","@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/veiligheidsproblematiek-is-ook-gezondheidsprobleem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elsrochette.brussels\/"},{"@type":"ListItem","position":2,"name":"Drugsoverlast aan Brussel-Zuid is ook een gezondheidsprobleem"}]},{"@type":"WebSite","@id":"https:\/\/www.elsrochette.brussels\/#website","url":"https:\/\/www.elsrochette.brussels\/","name":"Els Rochette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elsrochette.brussels\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0","name":"Robin CUVILLIER"}]}},"_links":{"self":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/3827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/comments?post=3827"}],"version-history":[{"count":7,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/3827\/revisions"}],"predecessor-version":[{"id":3836,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/3827\/revisions\/3836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media\/3834"}],"wp:attachment":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media?parent=3827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/categories?post=3827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/tags?post=3827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}