{"id":394,"date":"2020-02-12T09:51:00","date_gmt":"2020-02-12T09:51:00","guid":{"rendered":"https:\/\/www.dev.elsrochette.brussels\/?p=394"},"modified":"2021-07-01T14:00:03","modified_gmt":"2021-07-01T14:00:03","slug":"de-tijd-is-rijp-voor-een-politiezone-in-brussel","status":"publish","type":"post","link":"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/","title":{"rendered":"L\u2019heure est venue pour une seule zone de police \u00e0 Bruxelles"},"content":{"rendered":"<p><strong>Le ministre f\u00e9d\u00e9ral de l'Int\u00e9rieur a ordonn\u00e9 une \u00e9tude sur le fonctionnement des zones de police de Bruxelles. Je m'en f\u00e9licite. one.brussels est favorable \u00e0 une seule zone de police, pr\u00e9sid\u00e9e par le Ministre-Pr\u00e9sident de la R\u00e9gion.<\/strong><\/p>\n\n\n\n<p>Notre position est que les six zones de police doivent fusionner en une seul en vue d\u2019aboutir \u00e0 une politique de s\u00e9curit\u00e9 et de pr\u00e9vention efficace, coordonn\u00e9e et adapt\u00e9e \u00e0 la R\u00e9gion bruxelloise. Mais une zone de police unique n\u2019emp\u00eache en rien de travailler de mani\u00e8re diff\u00e9renci\u00e9e.<\/p>\n\n\n\n<p>Si quelque chose ne va pas dans l'action de la police en ce moment, c\u2019est que le contr\u00f4le d\u00e9mocratique est trop faible. Au niveau r\u00e9gional, les ministres renvoient la balle soit au niveau f\u00e9d\u00e9ral, soit aux conseils de police supra-communaux des zones de police. Lorsque la police d\u00e9passe les bornes, lorsque des abus se produisent ou que la violence est utilis\u00e9e contre les Bruxellois, le gouvernement bruxellois doit pouvoir prendre ses responsabilit\u00e9s. C'est le cas dans une zone de police unifi\u00e9e sous la supervision du Ministre-Pr\u00e9sident.&nbsp;<\/p>\n\n\n\n<p>J'ai interrog\u00e9 le Ministre-Pr\u00e9sident Vervoort sur le r\u00f4le de la R\u00e9gion de Bruxelles-Capitale dans l'\u00e9tude f\u00e9d\u00e9rale sur les zones de police de Bruxelles.<\/p>","protected":false},"excerpt":{"rendered":"De federaal Minister van Binnenlandse Zaken heeft een studie besteld over het functioneren van de Brusselse politiezones. Dat juich ik toe. one.brussels is voorstander van \u00e9\u00e9n politiezone, voorgezeten door de Minister-President van Brussel. Wij vinden dat de zes zones moeten opgaan in \u00e9\u00e9n politiezone, voor een effici\u00ebnt en geco\u00f6rdineerd veiligheids- en preventiebeleid op maat van&#8230; <a class=\"meer\" href=\"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/\">Lees meer<\/a>","protected":false},"author":1,"featured_media":883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,5],"tags":[],"class_list":["post-394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pact-voor-brussel","category-veiligheid"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>De tijd is rijp voor \u00e9\u00e9n politiezone in Brussel - Els Rochette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De tijd is rijp voor \u00e9\u00e9n politiezone in Brussel - Els Rochette\" \/>\n<meta property=\"og:description\" content=\"De federaal Minister van Binnenlandse Zaken heeft een studie besteld over het functioneren van de Brusselse politiezones. Dat juich ik toe. one.brussels is voorstander van \u00e9\u00e9n politiezone, voorgezeten door de Minister-President van Brussel. Wij vinden dat de zes zones moeten opgaan in \u00e9\u00e9n politiezone, voor een effici\u00ebnt en geco\u00f6rdineerd veiligheids- en preventiebeleid op maat van... Lees meer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/\" \/>\n<meta property=\"og:site_name\" content=\"Els Rochette\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-12T09:51:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-01T14:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2020\/02\/7S9A4145.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"1653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Robin CUVILLIER\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robin CUVILLIER\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/\",\"url\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/\",\"name\":\"De tijd is rijp voor \u00e9\u00e9n politiezone in Brussel - Els Rochette\",\"isPartOf\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2020\/02\/7S9A4145.jpg\",\"datePublished\":\"2020-02-12T09:51:00+00:00\",\"dateModified\":\"2021-07-01T14:00:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/#primaryimage\",\"url\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2020\/02\/7S9A4145.jpg\",\"contentUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2020\/02\/7S9A4145.jpg\",\"width\":2480,\"height\":1653},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elsrochette.brussels\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De tijd is rijp voor \u00e9\u00e9n politiezone in Brussel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\",\"url\":\"https:\/\/www.elsrochette.brussels\/\",\"name\":\"Els Rochette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elsrochette.brussels\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0\",\"name\":\"Robin CUVILLIER\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De tijd is rijp voor \u00e9\u00e9n politiezone in Brussel - Els Rochette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/","og_locale":"fr_FR","og_type":"article","og_title":"De tijd is rijp voor \u00e9\u00e9n politiezone in Brussel - Els Rochette","og_description":"De federaal Minister van Binnenlandse Zaken heeft een studie besteld over het functioneren van de Brusselse politiezones. Dat juich ik toe. one.brussels is voorstander van \u00e9\u00e9n politiezone, voorgezeten door de Minister-President van Brussel. Wij vinden dat de zes zones moeten opgaan in \u00e9\u00e9n politiezone, voor een effici\u00ebnt en geco\u00f6rdineerd veiligheids- en preventiebeleid op maat van... Lees meer","og_url":"https:\/\/www.elsrochette.brussels\/fr\/pact-voor-brussel\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/","og_site_name":"Els Rochette","article_published_time":"2020-02-12T09:51:00+00:00","article_modified_time":"2021-07-01T14:00:03+00:00","og_image":[{"width":2480,"height":1653,"url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2020\/02\/7S9A4145.jpg","type":"image\/jpeg"}],"author":"Robin CUVILLIER","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Robin CUVILLIER","Dur\u00e9e de lecture est.":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/","url":"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/","name":"De tijd is rijp voor \u00e9\u00e9n politiezone in Brussel - Els Rochette","isPartOf":{"@id":"https:\/\/www.elsrochette.brussels\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/#primaryimage"},"image":{"@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2020\/02\/7S9A4145.jpg","datePublished":"2020-02-12T09:51:00+00:00","dateModified":"2021-07-01T14:00:03+00:00","author":{"@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0"},"breadcrumb":{"@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/#primaryimage","url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2020\/02\/7S9A4145.jpg","contentUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2020\/02\/7S9A4145.jpg","width":2480,"height":1653},{"@type":"BreadcrumbList","@id":"https:\/\/www.elsrochette.brussels\/veiligheid\/de-tijd-is-rijp-voor-een-politiezone-in-brussel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elsrochette.brussels\/"},{"@type":"ListItem","position":2,"name":"De tijd is rijp voor \u00e9\u00e9n politiezone in Brussel"}]},{"@type":"WebSite","@id":"https:\/\/www.elsrochette.brussels\/#website","url":"https:\/\/www.elsrochette.brussels\/","name":"Els Rochette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elsrochette.brussels\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/389fd1b6ea7d132cef3dd1222f57fcb0","name":"Robin CUVILLIER"}]}},"_links":{"self":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/comments?post=394"}],"version-history":[{"count":4,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/394\/revisions"}],"predecessor-version":[{"id":738,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/394\/revisions\/738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media\/883"}],"wp:attachment":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media?parent=394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/categories?post=394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/tags?post=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}