{"id":3994,"date":"2023-12-05T13:29:03","date_gmt":"2023-12-05T13:29:03","guid":{"rendered":"https:\/\/dev.elsrochette.brussels\/?p=3994"},"modified":"2024-05-24T14:45:39","modified_gmt":"2024-05-24T14:45:39","slug":"uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations","status":"publish","type":"post","link":"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/","title":{"rendered":"Renforcer l\u2019assistance aux sans-abri dans les stations de m\u00e9tro\u00a0"},"content":{"rendered":"<p><strong>Le nombre de sans-abri augmente \u00e0 Bruxelles, de m\u00eame que la  consommation de drogue en public. Ils sont de plus en plus nombreux \u00e0 se r\u00e9fugier dans les stations de m\u00e9tro pour se prot\u00e9ger du froid et consommer de la drogue.&nbsp;<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Ce sont des personnes qui ont besoin d\u2019aide, pas des personnes dont nous devons nous d\u00e9barrasser.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<p>La consommation de drogue en public et le sans-abrisme sont des probl\u00e8mes de sant\u00e9 publique et de logement. Ces questions ne sont pas du ressort de la STIB. Mais la STIB peut n\u00e9anmoins faire partie de la solution.<\/p>\n\n\n\n<p>Comment ? J\u2019ai pos\u00e9 une question \u00e0 la ministre en&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=JwhEp81aet0&amp;list=PLQ3uOzWd9MNwnmkcdur6aaDB-oYCnDnSd\">commission de la mobilit\u00e9<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5,7 millions d\u2019euros<\/h2>\n\n\n\n<p>La STIB dispose d\u2019un budget de 5,7 millions d\u2019euros consacr\u00e9 sp\u00e9cifiquement \u00e0 soutenir et accompagner sur son r\u00e9seau les sans-abri et toxicomanes vers les lieux d\u2019accueil adapt\u00e9s. Mais aussi pour assurer la s\u00e9curit\u00e9 sur le r\u00e9seau de la STIB.<\/p>\n\n\n\n<p>Car c'est une n\u00e9cessit\u00e9.&nbsp;<\/p>\n\n\n\n<p>En effet, il y a de plus en plus d'incidents. La consommation de drogues est visible. Le nombre de personnes qui traversent les voies augmente. Des sans-abri ont perdu la vie parce qu'ils se sont retrouv\u00e9s coinc\u00e9s sous le volet d\u00e9roulant des stations de m\u00e9tro.&nbsp;<\/p>\n\n\n\n<p>Autant de drames qu\u2019il s\u2019agit de ne pas laisser se reproduire.<\/p>\n\n\n\n<p>Tant qu'il n'y aura pas de solution structurelle \u00e0 ces probl\u00e8mes de logement et de sant\u00e9 publique, les toxicomanes et les sans-abri continueront \u00e0 fr\u00e9quenter les stations. Nous r\u00e9soudrons rien en persistant \u00e0 consid\u00e9rer le probl\u00e8me comme une simple question s\u00e9curitaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9velopper le projet SubLINK&nbsp;<\/h2>\n\n\n\n<p>Le projet SubLINK, qui a port\u00e9 ses fruits, est en cours d'extension. C'est une bonne nouvelle, car les r\u00e9sultats sont excellents. Cette approche fonctionne. Coop\u00e9ration entre tous les acteurs impliqu\u00e9s : le projet Lama, Transit asbl, Diog\u00e8nes, New Samusocial, Bruss'Help, la STIB et la police. L'accent est mis sur l'accompagnement et l'assistance et pas seulement sur la s\u00e9curit\u00e9.&nbsp;<\/p>\n\n\n\n<p>Depuis juillet 2023, il y a d\u00e9j\u00e0 eu 1230 interventions et 432 personnes aid\u00e9es.&nbsp;&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Ce sont des personnes qui ont besoin d\u2019aide, pas des personnes dont nous devons nous d\u00e9barrasser. Je ne le dirai jamais assez.&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Nouvelles \u00e9quipes de la STIB<\/h2>\n\n\n\n<p>La STIB va \u00e9galement cr\u00e9er une nouvelle \u00e9quipe charg\u00e9e d'accompagner les toxicomanes et les sans-abri sur son r\u00e9seau.&nbsp;<\/p>\n\n\n\n<p>Il s'agit de 40 nouveaux agents de s\u00e9curit\u00e9 et de 25 nouveaux agents qui patrouilleront dans les stations de m\u00e9tro. Ils travailleront 24 heures sur 24 et 7 jours sur 7. Ce n'est pas un travail \u00e9vident.<\/p>\n\n\n\n<p>C'est pourquoi la formation est si importante.\nLeur objectif : entrer en contact avec les sans-abri et identifier les besoins les plus urgents.&nbsp;<\/p>\n\n\n\n<p>L'\u00e9quipe oriente ensuite vers une aide psychologique, m\u00e9dicale ou sociale, dans la mesure du possible. Cela compl\u00e8te le travail de SubLINK. En effet, SubLINK n'est pas pr\u00e9sent dans toutes les stations. Le service n'est pas non plus disponible 24 heures sur 24 et 7 jours sur 7.\u00a0\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Il y a de l\u2019espoir&nbsp;<\/h2>\n\n\n\n<p>Je suis heureuse que la STIB prenne au s\u00e9rieux le probl\u00e8me des sans-abri et des toxicomanes dans les stations. <\/p>\n\n\n\n<p>C'est une bonne chose qu'elle \u00e9coute \u00e9galement l'expertise des associations consacr\u00e9es aux sans-abri. <\/p>\n\n\n\n<p>Esp\u00e9rons qu'il y aura bient\u00f4t des r\u00e9sultats.<\/p>\n\n\n\n<p>Je suis le dossier.&nbsp;&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"Het aantal dak- en thuislozen in Brussel neemt toe. Ook het openbaar druggebruik. Steeds meer mensen zoeken hun toevlucht in metrostations om te ontsnappen aan de kou.&nbsp; Het gaat om mensen die moeten geholpen worden, niet om mensen die moeten opgekuist worden.&nbsp; Openbaar druggebruik en dak- en thuisloosheid zijn problemen van gezondheid en huisvesting. Dat&#8230; <a class=\"meer\" href=\"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/\">Lees meer<\/a>","protected":false},"author":11,"featured_media":4087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,1],"tags":[],"class_list":["post-3994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-armoede","category-mobiliteit-publieke-ruimte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Uitbreiding hulp voor dak- en thuislozen in metrostations\u00a0 - Els Rochette<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uitbreiding hulp voor dak- en thuislozen in metrostations\u00a0 - Els Rochette\" \/>\n<meta property=\"og:description\" content=\"Het aantal dak- en thuislozen in Brussel neemt toe. Ook het openbaar druggebruik. Steeds meer mensen zoeken hun toevlucht in metrostations om te ontsnappen aan de kou.&nbsp; Het gaat om mensen die moeten geholpen worden, niet om mensen die moeten opgekuist worden.&nbsp; Openbaar druggebruik en dak- en thuisloosheid zijn problemen van gezondheid en huisvesting. Dat... Lees meer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/\" \/>\n<meta property=\"og:site_name\" content=\"Els Rochette\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-05T13:29:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-24T14:45:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2024\/01\/35603617-e41a-4d58-b63c-8e7b35a04151.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/\",\"url\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/\",\"name\":\"Uitbreiding hulp voor dak- en thuislozen in metrostations\u00a0 - Els Rochette\",\"isPartOf\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2024\/01\/35603617-e41a-4d58-b63c-8e7b35a04151.jpg\",\"datePublished\":\"2023-12-05T13:29:03+00:00\",\"dateModified\":\"2024-05-24T14:45:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/d3676c6de2d6d584bdfcd732de791b09\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/#primaryimage\",\"url\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2024\/01\/35603617-e41a-4d58-b63c-8e7b35a04151.jpg\",\"contentUrl\":\"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2024\/01\/35603617-e41a-4d58-b63c-8e7b35a04151.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.elsrochette.brussels\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uitbreiding hulp voor dak- en thuislozen in metrostations\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#website\",\"url\":\"https:\/\/www.elsrochette.brussels\/\",\"name\":\"Els Rochette\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.elsrochette.brussels\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/d3676c6de2d6d584bdfcd732de791b09\",\"name\":\"Ann\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uitbreiding hulp voor dak- en thuislozen in metrostations\u00a0 - Els Rochette","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/","og_locale":"fr_FR","og_type":"article","og_title":"Uitbreiding hulp voor dak- en thuislozen in metrostations\u00a0 - Els Rochette","og_description":"Het aantal dak- en thuislozen in Brussel neemt toe. Ook het openbaar druggebruik. Steeds meer mensen zoeken hun toevlucht in metrostations om te ontsnappen aan de kou.&nbsp; Het gaat om mensen die moeten geholpen worden, niet om mensen die moeten opgekuist worden.&nbsp; Openbaar druggebruik en dak- en thuisloosheid zijn problemen van gezondheid en huisvesting. Dat... Lees meer","og_url":"https:\/\/www.elsrochette.brussels\/fr\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/","og_site_name":"Els Rochette","article_published_time":"2023-12-05T13:29:03+00:00","article_modified_time":"2024-05-24T14:45:39+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2024\/01\/35603617-e41a-4d58-b63c-8e7b35a04151.jpg","type":"image\/jpeg"}],"author":"Ann","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ann","Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/","url":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/","name":"Uitbreiding hulp voor dak- en thuislozen in metrostations\u00a0 - Els Rochette","isPartOf":{"@id":"https:\/\/www.elsrochette.brussels\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/#primaryimage"},"image":{"@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2024\/01\/35603617-e41a-4d58-b63c-8e7b35a04151.jpg","datePublished":"2023-12-05T13:29:03+00:00","dateModified":"2024-05-24T14:45:39+00:00","author":{"@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/d3676c6de2d6d584bdfcd732de791b09"},"breadcrumb":{"@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/#primaryimage","url":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2024\/01\/35603617-e41a-4d58-b63c-8e7b35a04151.jpg","contentUrl":"https:\/\/www.elsrochette.brussels\/wp-content\/uploads\/2024\/01\/35603617-e41a-4d58-b63c-8e7b35a04151.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/www.elsrochette.brussels\/mobiliteit-publieke-ruimte\/uitbreiding-hulp-voor-dak-en-thuislozen-in-metrostations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elsrochette.brussels\/"},{"@type":"ListItem","position":2,"name":"Uitbreiding hulp voor dak- en thuislozen in metrostations\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.elsrochette.brussels\/#website","url":"https:\/\/www.elsrochette.brussels\/","name":"Els Rochette","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elsrochette.brussels\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-BE"},{"@type":"Person","@id":"https:\/\/www.elsrochette.brussels\/#\/schema\/person\/d3676c6de2d6d584bdfcd732de791b09","name":"Ann"}]}},"_links":{"self":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/3994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/comments?post=3994"}],"version-history":[{"count":5,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/3994\/revisions"}],"predecessor-version":[{"id":4371,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/posts\/3994\/revisions\/4371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media\/4087"}],"wp:attachment":[{"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/media?parent=3994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/categories?post=3994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elsrochette.brussels\/fr\/wp-json\/wp\/v2\/tags?post=3994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}